{"id":1770,"date":"2024-11-07T10:55:32","date_gmt":"2024-11-07T09:55:32","guid":{"rendered":"https:\/\/digital-romandie.ch\/digir410\/work\/heetch-switzerland-sarl\/"},"modified":"2025-11-03T13:48:40","modified_gmt":"2025-11-03T12:48:40","slug":"heetch-switzerland-sarl","status":"publish","type":"work","link":"https:\/\/www.rister.ch\/es\/work\/heetch-switzerland-sarl\/","title":{"rendered":"Heetch Switzerland S\u00e0rl"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,2_3&#8243; module_class=\u00bbwork-full\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb max_width=\u00bb1225px\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; module_class=\u00bbwork-left\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb text_line_height=\u00bb24px\u00bb header_2_text_color=\u00bb#152842&#8243; header_2_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong>Cliente<\/strong><\/h2>\n<p>Heetch Suiza S\u00e0rl<\/p>\n<h2><strong>Alcance del proyecto<\/strong><\/h2>\n<p>Mandato administrativo global para permitir que HEETCH se concentre en su expansi\u00f3n en Suiza<\/p>\n<h2><strong>Soluciones<\/strong><\/h2>\n<p>Mandato global<\/p>\n<h2>\u200d<strong>Director local<\/strong><\/h2>\n<p>Mandato trimestral<\/p>\n<h2>\u200d<strong>Domiciliaci\u00f3n<\/strong><\/h2>\n<p>Mandato trimestral<\/p>\n<h2>\u200d<strong>Administraci\u00f3n<\/strong><\/h2>\n<p>IVA, Contabilidad, Sueldos<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; module_class=\u00bbwork-right\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bb|600|||||||\u00bb header_font_size=\u00bb38px\u00bb header_5_text_color=\u00bb#152842&#8243; header_6_text_color=\u00bb#152842&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"post-heading-box\" data-w-id=\"273ca440-7198-40d2-fe28-ee596111f420\">\n<h1 class=\"heading\">Heetch Switzerland S\u00e0rl<\/h1>\n<div>\n<p class=\"subtitle\">Creaci\u00f3n de una filial (S\u00e0rl) en Suiza y servicios de domiciliaci\u00f3n empresarial, gerente residente en Suiza y mandato de administraci\u00f3n global<\/p>\n<\/div>\n<\/div>\n<div class=\"rich-text-casestudy w-richtext\">\n<h3>C\u00f3mo Heetch Francia se benefici\u00f3 de la experiencia de RISTER para crear su filial en Ginebra<\/h3>\n<p>Heetch es una start-up francesa creada en Francia en 2013. Originalmente especializada en el coche compartido y luego como plataforma de viajes VTC.<\/p>\n<blockquote>\n<p>\u201cFuimos contactados por el CFO de Heetch Francia para solicitarnos una oferta para la constituci\u00f3n de una filial en Ginebra, su administraci\u00f3n, as\u00ed como servicios de gerente residente y domiciliaci\u00f3n hasta<br \/>la contrataci\u00f3n de su director en Suiza y la toma de posesi\u00f3n de sus oficinas en Ginebra. Tras la aceptaci\u00f3n de nuestra oferta completa y el an\u00e1lisis de la actividad y sus requisitos legales y administrativos, comenzamos los trabajos preparatorios para la constituci\u00f3n de la filial, una S\u00e0rl suiza y su empresa matriz en Francia.\u201d<\/p>\n<\/blockquote>\n<p><span style=\"color: #152842;\"><strong>Andr\u00e9s Taracido<\/strong><\/span><br \/>Director, RISTER<\/p>\n<h3>\u200dRESUMEN<\/h3>\n<p>En 2022, HEETCH, l\u00edder en Francia en servicios VTC, decidi\u00f3 establecerse en Suiza, particularmente en Ginebra, a trav\u00e9s de su aplicaci\u00f3n m\u00f3vil de viajes. RISTER se encarg\u00f3 de asesorar a HEETCH para constituir su filial en Ginebra, ofreciendo soluciones que incluyeron un mandato de gerente residente en Suiza y un mandato global de servicios administrativos para gestionar la inscripci\u00f3n al IVA, la contabilidad y la fiscalidad de la empresa.<\/p>\n<h4>\u200d<strong>PASOS CLAVE<\/strong><\/h4>\n<h3>CONSTITUCI\u00d3N DE FILIAL Y ADMINISTRACI\u00d3N GLOBAL<\/h3>\n<ol role=\"list\" start=\"\">\n<li>An\u00e1lisis de la actividad, asesoramiento, creaci\u00f3n de la filial, apertura de la cuenta bancaria e inscripci\u00f3n al IVA<\/li>\n<li>An\u00e1lisis de la base legal relativa a la actividad y seguimiento de los \u00faltimos desarrollos en Ginebra<\/li>\n<li>Implementaci\u00f3n de la domiciliaci\u00f3n y del mandato de gesti\u00f3n administrativa de la filial<\/li>\n<\/ol>\n<p>\u200dSOLUCI\u00d3N FIDUCIARIA GLOBAL<\/p>\n<h3><strong>Servicio de creaci\u00f3n de filial en Suiza<\/strong><\/h3>\n<p>An\u00e1lisis de la actividad, asesoramiento. Soluci\u00f3n integral para la constituci\u00f3n de la filial. Apertura de la cuenta bancaria. Inscripci\u00f3n al IVA. Seguimiento de la base legal aplicable a la actividad.<\/p>\n<h3><strong>Mandato administrativo global<\/strong><\/h3>\n<p>Servicio de domiciliaci\u00f3n empresarial, mandato de gerente residente en Suiza, IVA, contabilidad y fiscalidad.<\/p>\n<h3>\u200dRESULTADOS DE RISTER<\/h3>\n<table class=\"work-table aligncenter\" style=\"width: 100%; border-collapse: collapse;\" border=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 33.3333%; border-right: 1px solid #d6e0da;\">\n<div>\n<h1>100%<\/h1>\n<p>Tasa de \u00e9xito en la creaci\u00f3n completa de la filial<\/p>\n<\/div>\n<\/td>\n<td style=\"width: 33.4623%; border-right: 1px solid #d6e0da;\">\n<div>\n<h1>100%<\/h1>\n<p>Tasa de \u00e9xito en la apertura de la cuenta bancaria<\/p>\n<\/div>\n<\/td>\n<td style=\"width: 33.2043%;\">\n<div>\n<h1>100%<\/h1>\n<p>Tasa de \u00e9xito en la implementaci\u00f3n de la domiciliaci\u00f3n empresarial en solo 1 semana<\/p>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"w-embed\">\n<div>\u00a0<\/div>\n<h3>\u200dCONSIDERACIONES FUTURAS<\/h3>\n<\/div>\n<p><strong>Contabilidad\/IVA<\/strong><\/p>\n<p>Contabilidad seg\u00fan las normas aplicables en Suiza y declaraciones trimestrales de IVA<\/p>\n<p>\u200d<strong>Fiscalidad<\/strong><\/p>\n<p>Impuestos ICC\/IFD sobre beneficios e impuestos sobre el capital, retenci\u00f3n en la fuente, impuesto anticipado, derecho de timbre, distribuciones de dividendos.<\/p>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"featured_media":598,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false},"class_list":["post-1770","work","type-work","status-publish","has-post-thumbnail","hentry"],"rank_math":{"rank_math_title":"Testimonio de cliente %title% %page% %sep% %sitename%","rank_math_description":"","rank_math_focus_keyword":""},"acf":[],"_links":{"self":[{"href":"https:\/\/www.rister.ch\/es\/wp-json\/wp\/v2\/work\/1770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rister.ch\/es\/wp-json\/wp\/v2\/work"}],"about":[{"href":"https:\/\/www.rister.ch\/es\/wp-json\/wp\/v2\/types\/work"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rister.ch\/es\/wp-json\/wp\/v2\/media\/598"}],"wp:attachment":[{"href":"https:\/\/www.rister.ch\/es\/wp-json\/wp\/v2\/media?parent=1770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}